{"id":6564,"date":"2024-06-11T07:51:22","date_gmt":"2024-06-10T23:51:22","guid":{"rendered":"https:\/\/www.liwin-china.com\/?post_type=product&#038;p=6564"},"modified":"2026-04-17T19:11:14","modified_gmt":"2026-04-17T11:11:14","slug":"liwiny-car-rgb-led-12v-t10-cob-led-bulb-5050-reading-universal-wedge-light-signal-lamp-led-car-light-t10-remote","status":"publish","type":"product","link":"https:\/\/www.liwin-china.com\/it\/prodotto\/liwiny-car-rgb-led-12v-t10-cob-led-bulb-5050-reading-universal-wedge-light-signal-lamp-led-car-light-t10-remote\/","title":{"rendered":"Liwiny Car RGB LED 12V T10 COB LED Bulb 5050 Reading Universal Wedge Light Signal Lamp Led auto light t10 remote"},"content":{"rendered":"<p>Liwiny Car RGB LED 12V T10 COB LED Bulb 5050 Reading Universal Wedge Light Signal Lamp Led auto light t10 remote<\/p>\n<p>Nome della marca: Liwiny<\/p>\n<p>Articolo: Luce di lettura per auto a LED<\/p>\n<p>Luce della cupola, luce di lettura, luce del bagagliaio, luce della targa, luce interna<br \/>\nNumero di parte OEM: T10 COB 12RGB<br \/>\nTensione: 12V<br \/>\nPotenza: 1,56 W<br \/>\nLumen\uff1a144 LM<br \/>\nChip a LED\uff1aCOB<\/p>\n<p>Qt\u00e0 Led: 12 pezzi<br \/>\nTemperatura colore: RGB<\/p>\n<p>Presa utile\uff1aT10<\/p>\n<p>Dimensione: 10*34 mm<\/p>\n<p>Pacchetto: Scatola di colore piccola<br \/>\nOEM: disponibile<br \/>\nDurata di vita: pi\u00f9 di 30000h<br \/>\nGaranzia: 1 anno<br \/>\nMarca dell'auto: Universale<br \/>\nLuogo di origine: Guangdong, Cina<br \/>\nTempi di consegna: secondo i dettagli dell'ordine del cliente<\/p>\n<p>&nbsp;<\/p>\n<p>Funzione: la funzione<span class=\"magic-16\" data-spm-anchor-id=\"a2700.details.0.i101.6c827f69FPcQq3\">Senza Hyper Flash; pi\u00f9 luminoso 200%;<\/span><\/p>\n<div data-spm-anchor-id=\"a2700.pc-decorate.0.i96.4dbf3333oJtTj4\"><span class=\"magic-16\">Dissipazione rapida del calore;<\/span><\/div>\n<div data-spm-anchor-id=\"a2700.pc-decorate.0.i96.4dbf3333oJtTj4\"><span class=\"magic-16\">Alluminio 6063 per l'aviazione<br \/>\n<\/span><\/p>\n<div data-spm-anchor-id=\"a2700.pc-decorate.0.i93.4dbf3333oJtTj4\">\n<p><span class=\"magic-16\">Plug and Play;100% Canbus;<\/span><\/p>\n<div data-spm-anchor-id=\"a2700.pc-decorate.0.i88.4dbf3333oJtTj4\"><span class=\"magic-16\">Dimensione globale dello standard alogeno;<\/span><\/div>\n<div data-spm-anchor-id=\"a2700.pc-decorate.0.i88.4dbf3333oJtTj4\"><span class=\"magic-16\">Controllo della temperatura nel settore automobilistico;<\/span><\/div>\n<div data-spm-anchor-id=\"a2700.pc-decorate.0.i88.4dbf3333oJtTj4\"><span class=\"magic-16\">Anti-Hyper Flash; Alluminio termico cavo;<\/span><\/div>\n<\/div>\n<\/div>\n<div data-spm-anchor-id=\"a2700.pc-decorate.0.i88.4dbf3333oJtTj4\"><\/div>\n<div data-spm-anchor-id=\"a2700.pc-decorate.0.i88.4dbf3333oJtTj4\"><\/div>\n<div data-spm-anchor-id=\"a2700.pc-decorate.0.i96.4dbf3333oJtTj4\">\n<div data-spm-anchor-id=\"a2700.pc-decorate.0.i88.4dbf3333oJtTj4\">NOTA:<br \/>\n1) Il prezzo si basa sulla modalit\u00e0 di illuminazione. Contattate se avete bisogno della modalit\u00e0 strobo.<br \/>\n2) Ricordateci se avete bisogno di una tensione speciale per veicoli speciali.<br \/>\n3) Se avete bisogno di un canbus integrato, contattate per maggiori dettagli.<br \/>\n4) Di solito imballiamo con sacchetto antistatico con carica gratuita, contatti di pls se avete bisogno di pacchetto personalizzato.Grazie.<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<h1><strong>Perch\u00e9 scegliere LIWINY?<\/strong><\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4463\" src=\"https:\/\/www.liwin-china.com\/wp-content\/uploads\/2023\/12\/liwiny-oem-ballast.webp\" alt=\"\" width=\"1980\" height=\"600\" srcset=\"https:\/\/www.liwin-china.com\/wp-content\/uploads\/2023\/12\/liwiny-oem-ballast.webp 1980w, https:\/\/www.liwin-china.com\/wp-content\/uploads\/2023\/12\/liwiny-oem-ballast-300x91.webp 300w, https:\/\/www.liwin-china.com\/wp-content\/uploads\/2023\/12\/liwiny-oem-ballast-1024x310.webp 1024w, https:\/\/www.liwin-china.com\/wp-content\/uploads\/2023\/12\/liwiny-oem-ballast-768x233.webp 768w, https:\/\/www.liwin-china.com\/wp-content\/uploads\/2023\/12\/liwiny-oem-ballast-1536x465.webp 1536w, https:\/\/www.liwin-china.com\/wp-content\/uploads\/2023\/12\/liwiny-oem-ballast-600x182.webp 600w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/><\/p>\n<ul>\n<li>Dal materiale al prodotto finito, seguiamo un rigoroso controllo di qualit\u00e0, assicurando che il tasso di difettosit\u00e0 sia inferiore a 1%.<\/li>\n<li>Benvenuti oders OEM\/ODM, accettiamo una serie di requisiti di personalizzazione come l'aspetto, il potere, l'azionamento, il ventilatore, il chip, la temperatura del colore, il logo, l'imballaggio.<\/li>\n<li>Offriamo garanzie di 12-36 mesi che includono la sostituzione diretta. Non \u00e8 necessario rispedire i prodotti difettosi.<\/li>\n<li>Ci concentriamo sulle tendenze del mercato e sviluppiamo 3-5 nuovi prodotti ogni stagione.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Richiedete un preventivo oggi stesso!<\/h2>\n<p>Tutti i prodotti LIWINY sono disponibili per ordini in blocco\/vendite all'ingrosso! Se volete vendere i nostri prodotti o diventare nostri distributori, contattateci, otterrete i seguenti vantaggi:<\/p>\n<p>MOQ basso e consegna veloce<br \/>\nProdotti innovativi<br \/>\nMiglior prezzo all'ingrosso<br \/>\nServizio OEM\/ODM<\/p>","protected":false},"excerpt":{"rendered":"<p>Nome della marca: Liwiny<\/p>\n<p>Articolo: Luce di lettura per auto a LED<\/p>\n<p>Luce della cupola, luce di lettura, luce del bagagliaio, luce della targa, luce interna<br \/>\nNumero di parte OEM: T10 COB 12RGB<br \/>\nTensione: 12V<br \/>\nPotenza: 1,56 W<br \/>\nLumen\uff1a144 LM<br \/>\nChip a LED\uff1aCOB<\/p>\n<p>Qt\u00e0 Led: 12 pezzi<br \/>\nTemperatura colore: RGB<\/p>\n<p>Presa utile\uff1aT10<\/p>\n<p>Dimensione: 10*34 mm<\/p>\n<p>Materiale: lega di alluminio<br \/>\nPacchetto: Scatola di colore piccola<br \/>\nOEM: disponibile<br \/>\nDurata di vita: pi\u00f9 di 30000h<br \/>\nGaranzia: 1 anno<br \/>\nMarca dell'auto: Universale<br \/>\nLuogo di origine: Guangdong, Cina<br \/>\nTempi di consegna: secondo i dettagli dell'ordine del cliente<\/p>","protected":false},"featured_media":6573,"template":"","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_uag_custom_page_level_css":"","_joinchat":[]},"product_cat":[474,77],"product_tag":[],"featured_image_urls":{"full":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2.webp",800,800,false],"thumbnail":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2-150x150.webp",150,150,true],"medium":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2-300x300.webp",300,300,true],"medium_large":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2-768x768.webp",768,768,true],"large":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2.webp",800,800,false],"1536x1536":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2.webp",800,800,false],"2048x2048":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2.webp",800,800,false],"trp-custom-language-flag":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2.webp",12,12,false],"woocommerce_archive_thumbnail":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2-300x300.webp",300,300,true],"woocommerce_thumbnail":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2-300x300.webp",300,300,true],"woocommerce_single":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2-600x600.webp",600,600,true],"woocommerce_gallery_thumbnail":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2-100x100.webp",100,100,true]},"post_excerpt_stackable":"<p>Brand Name\uff1aLiwiny<\/p>\n<p>Item\uff1aLED car reading light<\/p>\n<p>Dome light , Reading light ,Trunk light,License plate light, Interior light<br \/>\nOEM Part No.\uff1aT10 COB 12RGB<br \/>\nVoltage\uff1a12V<br \/>\nPower\uff1a1.56W<br \/>\nLumen\uff1a144 LM<br \/>\nLed Chip\uff1aCOB<\/p>\n<p>Led Qty\uff1a12PCS<br \/>\nColor Temperature\uff1aRGB<\/p>\n<p>Useful Socket\uff1aT10<\/p>\n<p>Size\uff1a10*34 mm<\/p>\n<p>Material\uff1aAluminium Alloy<br \/>\nPackage\uff1aSmall Color Box<br \/>\nOEM\uff1aAvailable<br \/>\nLife Span\uff1aMore than 30000h<br \/>\nWarranty\uff1a1 year<br \/>\nCar Make\uff1aUniversal<br \/>\nPlace of Origin:Guangdong, China<br \/>\nLead-time\uff1aAccording to customers order detail<\/p>\n","category_list":"","author_info":{"name":"","url":""},"comments_num":"0 commenti","uagb_featured_image_src":{"full":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2.webp",800,800,false],"thumbnail":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2-150x150.webp",150,150,true],"medium":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2-300x300.webp",300,300,true],"medium_large":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2-768x768.webp",768,768,true],"large":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2.webp",800,800,false],"1536x1536":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2.webp",800,800,false],"2048x2048":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2.webp",800,800,false],"trp-custom-language-flag":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2.webp",12,12,false],"woocommerce_archive_thumbnail":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2-300x300.webp",300,300,true],"woocommerce_thumbnail":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2-300x300.webp",300,300,true],"woocommerce_single":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2-600x600.webp",600,600,true],"woocommerce_gallery_thumbnail":["https:\/\/www.liwin-china.com\/wp-content\/uploads\/2024\/06\/T10-COB-12RGB-2-100x100.webp",100,100,true]},"uagb_author_info":{"display_name":"adminn","author_link":"https:\/\/www.liwin-china.com\/it\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Brand Name\uff1aLiwiny Item\uff1aLED car reading light Dome light , Reading light ,Trunk light,License plate light, Interior light OEM Part No.\uff1aT10 COB 12RGB Voltage\uff1a12V Power\uff1a1.56W Lumen\uff1a144 LM Led Chip\uff1aCOB Led Qty\uff1a12PCS Color Temperature\uff1aRGB Useful Socket\uff1aT10 Size\uff1a10*34 mm Material\uff1aAluminium Alloy Package\uff1aSmall Color Box OEM\uff1aAvailable Life Span\uff1aMore than 30000h Warranty\uff1a1 year Car Make\uff1aUniversal Place of Origin:Guangdong, China Lead-time\uff1aAccording&hellip;","_links":{"self":[{"href":"https:\/\/www.liwin-china.com\/it\/wp-json\/wp\/v2\/product\/6564"}],"collection":[{"href":"https:\/\/www.liwin-china.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.liwin-china.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.liwin-china.com\/it\/wp-json\/wp\/v2\/media\/6573"}],"wp:attachment":[{"href":"https:\/\/www.liwin-china.com\/it\/wp-json\/wp\/v2\/media?parent=6564"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.liwin-china.com\/it\/wp-json\/wp\/v2\/product_cat?post=6564"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.liwin-china.com\/it\/wp-json\/wp\/v2\/product_tag?post=6564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}